{"id":13371,"date":"2023-03-05T12:51:00","date_gmt":"2023-03-05T12:51:00","guid":{"rendered":"https:\/\/fcballkani.com\/?p=13371"},"modified":"2023-03-05T12:51:02","modified_gmt":"2023-03-05T12:51:02","slug":"matchday-10","status":"publish","type":"post","link":"https:\/\/fcballkani.com\/en\/matchday-10\/","title":{"rendered":"#MATCHDAY"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":13372,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-13371","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>#MATCHDAY - FC BALLKANI<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fcballkani.com\/en\/matchday-10\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"#MATCHDAY - FC BALLKANI\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fcballkani.com\/en\/matchday-10\/\" \/>\n<meta property=\"og:site_name\" content=\"FC BALLKANI\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/fcballkani\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-05T12:51:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-05T12:51:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fcballkani.com\/wp-content\/uploads\/2023\/03\/334414235_163331026563376_1717358944232697168_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"843\" \/>\n\t<meta property=\"og:image:height\" content=\"843\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"roitiv.backup\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"roitiv.backup\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/fcballkani.com\/matchday-10\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/fcballkani.com\/matchday-10\/\"},\"author\":{\"name\":\"roitiv.backup\",\"@id\":\"https:\/\/fcballkani.com\/#\/schema\/person\/ab46cb926beb281f25abea3d64db9474\"},\"headline\":\"#MATCHDAY\",\"datePublished\":\"2023-03-05T12:51:00+00:00\",\"dateModified\":\"2023-03-05T12:51:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/fcballkani.com\/matchday-10\/\"},\"wordCount\":1,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/fcballkani.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/fcballkani.com\/matchday-10\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/fcballkani.com\/wp-content\/uploads\/2023\/03\/334414235_163331026563376_1717358944232697168_n.jpg\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/fcballkani.com\/matchday-10\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/fcballkani.com\/matchday-10\/\",\"url\":\"https:\/\/fcballkani.com\/matchday-10\/\",\"name\":\"#MATCHDAY - FC BALLKANI\",\"isPartOf\":{\"@id\":\"https:\/\/fcballkani.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/fcballkani.com\/matchday-10\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/fcballkani.com\/matchday-10\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/fcballkani.com\/wp-content\/uploads\/2023\/03\/334414235_163331026563376_1717358944232697168_n.jpg\",\"datePublished\":\"2023-03-05T12:51:00+00:00\",\"dateModified\":\"2023-03-05T12:51:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/fcballkani.com\/matchday-10\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/fcballkani.com\/matchday-10\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/fcballkani.com\/matchday-10\/#primaryimage\",\"url\":\"https:\/\/fcballkani.com\/wp-content\/uploads\/2023\/03\/334414235_163331026563376_1717358944232697168_n.jpg\",\"contentUrl\":\"https:\/\/fcballkani.com\/wp-content\/uploads\/2023\/03\/334414235_163331026563376_1717358944232697168_n.jpg\",\"width\":843,\"height\":843},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/fcballkani.com\/matchday-10\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/fcballkani.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"#MATCHDAY\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/fcballkani.com\/#website\",\"url\":\"https:\/\/fcballkani.com\/\",\"name\":\"FC BALLKANI\",\"description\":\"Football Club\",\"publisher\":{\"@id\":\"https:\/\/fcballkani.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/fcballkani.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/fcballkani.com\/#organization\",\"name\":\"FC Ballkani\",\"url\":\"https:\/\/fcballkani.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/fcballkani.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/fcballkani.com\/wp-content\/uploads\/2022\/07\/fc-ballkani.png\",\"contentUrl\":\"https:\/\/fcballkani.com\/wp-content\/uploads\/2022\/07\/fc-ballkani.png\",\"width\":642,\"height\":642,\"caption\":\"FC Ballkani\"},\"image\":{\"@id\":\"https:\/\/fcballkani.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/fcballkani\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/fcballkani.com\/#\/schema\/person\/ab46cb926beb281f25abea3d64db9474\",\"name\":\"roitiv.backup\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/514059babf979a5fc9a6dfe80d5e2070fc9983ea2040ec553a914a6dca739e13?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/514059babf979a5fc9a6dfe80d5e2070fc9983ea2040ec553a914a6dca739e13?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/514059babf979a5fc9a6dfe80d5e2070fc9983ea2040ec553a914a6dca739e13?s=96&d=mm&r=g\",\"caption\":\"roitiv.backup\"},\"sameAs\":[\"https:\/\/fcballkani.com\"],\"url\":\"https:\/\/fcballkani.com\/en\/author\/roitiv-backup\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"#MATCHDAY - FC BALLKANI","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fcballkani.com\/en\/matchday-10\/","og_locale":"en_US","og_type":"article","og_title":"#MATCHDAY - FC BALLKANI","og_url":"https:\/\/fcballkani.com\/en\/matchday-10\/","og_site_name":"FC BALLKANI","article_publisher":"https:\/\/www.facebook.com\/fcballkani","article_published_time":"2023-03-05T12:51:00+00:00","article_modified_time":"2023-03-05T12:51:02+00:00","og_image":[{"width":843,"height":843,"url":"https:\/\/fcballkani.com\/wp-content\/uploads\/2023\/03\/334414235_163331026563376_1717358944232697168_n.jpg","type":"image\/jpeg"}],"author":"roitiv.backup","twitter_card":"summary_large_image","twitter_misc":{"Written by":"roitiv.backup"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fcballkani.com\/matchday-10\/#article","isPartOf":{"@id":"https:\/\/fcballkani.com\/matchday-10\/"},"author":{"name":"roitiv.backup","@id":"https:\/\/fcballkani.com\/#\/schema\/person\/ab46cb926beb281f25abea3d64db9474"},"headline":"#MATCHDAY","datePublished":"2023-03-05T12:51:00+00:00","dateModified":"2023-03-05T12:51:02+00:00","mainEntityOfPage":{"@id":"https:\/\/fcballkani.com\/matchday-10\/"},"wordCount":1,"commentCount":0,"publisher":{"@id":"https:\/\/fcballkani.com\/#organization"},"image":{"@id":"https:\/\/fcballkani.com\/matchday-10\/#primaryimage"},"thumbnailUrl":"https:\/\/fcballkani.com\/wp-content\/uploads\/2023\/03\/334414235_163331026563376_1717358944232697168_n.jpg","inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fcballkani.com\/matchday-10\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fcballkani.com\/matchday-10\/","url":"https:\/\/fcballkani.com\/matchday-10\/","name":"#MATCHDAY - FC BALLKANI","isPartOf":{"@id":"https:\/\/fcballkani.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fcballkani.com\/matchday-10\/#primaryimage"},"image":{"@id":"https:\/\/fcballkani.com\/matchday-10\/#primaryimage"},"thumbnailUrl":"https:\/\/fcballkani.com\/wp-content\/uploads\/2023\/03\/334414235_163331026563376_1717358944232697168_n.jpg","datePublished":"2023-03-05T12:51:00+00:00","dateModified":"2023-03-05T12:51:02+00:00","breadcrumb":{"@id":"https:\/\/fcballkani.com\/matchday-10\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fcballkani.com\/matchday-10\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/fcballkani.com\/matchday-10\/#primaryimage","url":"https:\/\/fcballkani.com\/wp-content\/uploads\/2023\/03\/334414235_163331026563376_1717358944232697168_n.jpg","contentUrl":"https:\/\/fcballkani.com\/wp-content\/uploads\/2023\/03\/334414235_163331026563376_1717358944232697168_n.jpg","width":843,"height":843},{"@type":"BreadcrumbList","@id":"https:\/\/fcballkani.com\/matchday-10\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fcballkani.com\/"},{"@type":"ListItem","position":2,"name":"#MATCHDAY"}]},{"@type":"WebSite","@id":"https:\/\/fcballkani.com\/#website","url":"https:\/\/fcballkani.com\/","name":"FC BALLKANI","description":"Football Club","publisher":{"@id":"https:\/\/fcballkani.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fcballkani.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/fcballkani.com\/#organization","name":"FC Ballkani","url":"https:\/\/fcballkani.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/fcballkani.com\/#\/schema\/logo\/image\/","url":"https:\/\/fcballkani.com\/wp-content\/uploads\/2022\/07\/fc-ballkani.png","contentUrl":"https:\/\/fcballkani.com\/wp-content\/uploads\/2022\/07\/fc-ballkani.png","width":642,"height":642,"caption":"FC Ballkani"},"image":{"@id":"https:\/\/fcballkani.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/fcballkani"]},{"@type":"Person","@id":"https:\/\/fcballkani.com\/#\/schema\/person\/ab46cb926beb281f25abea3d64db9474","name":"roitiv.backup","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/514059babf979a5fc9a6dfe80d5e2070fc9983ea2040ec553a914a6dca739e13?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/514059babf979a5fc9a6dfe80d5e2070fc9983ea2040ec553a914a6dca739e13?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/514059babf979a5fc9a6dfe80d5e2070fc9983ea2040ec553a914a6dca739e13?s=96&d=mm&r=g","caption":"roitiv.backup"},"sameAs":["https:\/\/fcballkani.com"],"url":"https:\/\/fcballkani.com\/en\/author\/roitiv-backup\/"}]}},"_links":{"self":[{"href":"https:\/\/fcballkani.com\/en\/wp-json\/wp\/v2\/posts\/13371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fcballkani.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fcballkani.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fcballkani.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fcballkani.com\/en\/wp-json\/wp\/v2\/comments?post=13371"}],"version-history":[{"count":1,"href":"https:\/\/fcballkani.com\/en\/wp-json\/wp\/v2\/posts\/13371\/revisions"}],"predecessor-version":[{"id":13373,"href":"https:\/\/fcballkani.com\/en\/wp-json\/wp\/v2\/posts\/13371\/revisions\/13373"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fcballkani.com\/en\/wp-json\/wp\/v2\/media\/13372"}],"wp:attachment":[{"href":"https:\/\/fcballkani.com\/en\/wp-json\/wp\/v2\/media?parent=13371"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fcballkani.com\/en\/wp-json\/wp\/v2\/categories?post=13371"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fcballkani.com\/en\/wp-json\/wp\/v2\/tags?post=13371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}