{"id":1746,"date":"2022-07-15T09:16:02","date_gmt":"2022-07-15T07:16:02","guid":{"rendered":"https:\/\/fcballkani.com\/?page_id=1746"},"modified":"2026-05-11T10:21:55","modified_gmt":"2026-05-11T08:21:55","slug":"ballkani","status":"publish","type":"page","link":"https:\/\/fcballkani.com\/en\/","title":{"rendered":"Ballkani"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"1746\" class=\"elementor elementor-1746\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ca875a4 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"ca875a4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-88b7d05\" data-id=\"88b7d05\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-89fc9ed elementor-widget__width-inherit elementor--h-position-center elementor--v-position-middle elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"89fc9ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;dots&quot;,&quot;transition_speed&quot;:1500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\" dir=\"ltr\" data-animation=\"fadeInRight\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-a945ddc swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg elementor-ken-burns elementor-ken-burns--in\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-adb2b51 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg elementor-ken-burns elementor-ken-burns--in\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-a9c02ec swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg elementor-ken-burns elementor-ken-burns--in\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-c647745 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg elementor-ken-burns elementor-ken-burns--in\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-5559bc4 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg elementor-ken-burns elementor-ken-burns--in\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-60d3b89 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg elementor-ken-burns elementor-ken-burns--in\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-c7513e6 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg elementor-ken-burns elementor-ken-burns--in\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d0bc55e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d0bc55e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cba262a\" data-id=\"cba262a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b348fa6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b348fa6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e709507\" data-id=\"e709507\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ca1a770 elementor-widget elementor-widget-heading\" data-id=\"ca1a770\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Next Match<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-fee4e15\" data-id=\"fee4e15\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fe19b57 elementor-align-right elementor-mobile-align-left elementor-widget elementor-widget-button\" data-id=\"fe19b57\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/fcballkani.com\/en\/oraret-e-ndeshjeve\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Learn more<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-3849e2f elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"3849e2f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-becd3a5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"becd3a5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-f380e5e\" data-id=\"f380e5e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-befaefb elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"befaefb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img fetchpriority=\"high\" decoding=\"async\" width=\"642\" height=\"642\" src=\"https:\/\/fcballkani.com\/wp-content\/uploads\/2022\/07\/fc-ballkani.png\" class=\"attachment-full size-full wp-image-3698\" alt=\"\" srcset=\"https:\/\/fcballkani.com\/wp-content\/uploads\/2022\/07\/fc-ballkani.png 642w, https:\/\/fcballkani.com\/wp-content\/uploads\/2022\/07\/fc-ballkani-300x300.png 300w, https:\/\/fcballkani.com\/wp-content\/uploads\/2022\/07\/fc-ballkani-150x150.png 150w\" sizes=\"(max-width: 642px) 100vw, 642px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">FC Ballkani<\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-d4db9a4\" data-id=\"d4db9a4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ebfb9c elementor-widget elementor-widget-heading\" data-id=\"3ebfb9c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">VS<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-be92a90\" data-id=\"be92a90\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-025b8f2 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"025b8f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"150\" height=\"196\" src=\"https:\/\/fcballkani.com\/wp-content\/uploads\/2025\/09\/KF_Prishtina_e_Re_Logo.svg.png\" class=\"attachment-full size-full wp-image-18993\" alt=\"\" srcset=\"https:\/\/fcballkani.com\/wp-content\/uploads\/2025\/09\/KF_Prishtina_e_Re_Logo.svg.png 150w, https:\/\/fcballkani.com\/wp-content\/uploads\/2025\/09\/KF_Prishtina_e_Re_Logo.svg-9x12.png 9w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">KF Prishtina e Re<\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-2fcd73c elementor-widget elementor-widget-heading\" data-id=\"2fcd73c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><br><br>\nLokacioni: Stadiumi i Qytetit, Suharek\u00eb<br><br>Data: 17.05.2026<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d99eecf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d99eecf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-ab7b6d9\" data-id=\"ab7b6d9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-63851bf elementor-countdown--label-block elementor-widget elementor-widget-countdown\" data-id=\"63851bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"countdown.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-countdown-wrapper\" data-date=\"1779026400\">\n\t\t\t<div class=\"elementor-countdown-item\"><span class=\"elementor-countdown-digits elementor-countdown-days\"><\/span> <span class=\"elementor-countdown-label\">Days<\/span><\/div><div class=\"elementor-countdown-item\"><span class=\"elementor-countdown-digits elementor-countdown-hours\"><\/span> <span class=\"elementor-countdown-label\">Hours<\/span><\/div><div class=\"elementor-countdown-item\"><span class=\"elementor-countdown-digits elementor-countdown-minutes\"><\/span> <span class=\"elementor-countdown-label\">Minutes<\/span><\/div><div class=\"elementor-countdown-item\"><span class=\"elementor-countdown-digits elementor-countdown-seconds\"><\/span> <span class=\"elementor-countdown-label\">Seconds<\/span><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d59f4d1 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"d59f4d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-ticket-alt\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Tickets<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4354403 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4354403\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d1f03e3\" data-id=\"d1f03e3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-59970ca elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"59970ca\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6de9edd\" data-id=\"6de9edd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3f47861 elementor-widget elementor-widget-heading\" data-id=\"3f47861\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Club jerseys<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8a6bb1b\" data-id=\"8a6bb1b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-79e4519 elementor-align-center elementor-mobile-align-left elementor-widget elementor-widget-button\" data-id=\"79e4519\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/fcballkani.com\/en\/comingsoon\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">See more<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-28c540d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"28c540d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3de66ce\" data-id=\"3de66ce\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-344aa47 elementor-widget elementor-widget-spacer\" data-id=\"344aa47\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7ca4efc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7ca4efc\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5ea259c\" data-id=\"5ea259c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f48c62f elementor-widget elementor-widget-image\" data-id=\"f48c62f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2000\" height=\"2000\" src=\"https:\/\/fcballkani.com\/wp-content\/uploads\/2024\/10\/1.png\" class=\"attachment-full size-full wp-image-17884\" alt=\"\" srcset=\"https:\/\/fcballkani.com\/wp-content\/uploads\/2024\/10\/1.png 2000w, https:\/\/fcballkani.com\/wp-content\/uploads\/2024\/10\/1-300x300.png 300w, https:\/\/fcballkani.com\/wp-content\/uploads\/2024\/10\/1-1024x1024.png 1024w, https:\/\/fcballkani.com\/wp-content\/uploads\/2024\/10\/1-150x150.png 150w, https:\/\/fcballkani.com\/wp-content\/uploads\/2024\/10\/1-768x768.png 768w, https:\/\/fcballkani.com\/wp-content\/uploads\/2024\/10\/1-1536x1536.png 1536w, https:\/\/fcballkani.com\/wp-content\/uploads\/2024\/10\/1-12x12.png 12w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-cc5e5bd\" data-id=\"cc5e5bd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aec3af5 elementor-widget elementor-widget-heading\" data-id=\"aec3af5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Home<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2e53a3a\" data-id=\"2e53a3a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-791dc3e elementor-widget elementor-widget-spacer\" data-id=\"791dc3e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2ab948f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2ab948f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-582e3e1\" data-id=\"582e3e1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8e117bf elementor-widget elementor-widget-image\" data-id=\"8e117bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/fcballkani.com\/wp-content\/uploads\/2024\/10\/5-1024x1024.png\" class=\"attachment-large size-large wp-image-17885\" alt=\"\" srcset=\"https:\/\/fcballkani.com\/wp-content\/uploads\/2024\/10\/5-1024x1024.png 1024w, https:\/\/fcballkani.com\/wp-content\/uploads\/2024\/10\/5-300x300.png 300w, https:\/\/fcballkani.com\/wp-content\/uploads\/2024\/10\/5-150x150.png 150w, https:\/\/fcballkani.com\/wp-content\/uploads\/2024\/10\/5-768x768.png 768w, https:\/\/fcballkani.com\/wp-content\/uploads\/2024\/10\/5-1536x1536.png 1536w, https:\/\/fcballkani.com\/wp-content\/uploads\/2024\/10\/5-12x12.png 12w, https:\/\/fcballkani.com\/wp-content\/uploads\/2024\/10\/5.png 2000w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0c7a9db\" data-id=\"0c7a9db\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1aa9ad3 elementor-widget elementor-widget-heading\" data-id=\"1aa9ad3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Guest<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-ede1d60\" data-id=\"ede1d60\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fada876 elementor-widget elementor-widget-spacer\" data-id=\"fada876\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7ced4cd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7ced4cd\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-80526c0\" data-id=\"80526c0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a3af88b elementor-widget elementor-widget-image\" data-id=\"a3af88b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/fcballkani.com\/wp-content\/uploads\/2024\/10\/9-1024x1024.png\" class=\"attachment-large size-large wp-image-17886\" alt=\"\" srcset=\"https:\/\/fcballkani.com\/wp-content\/uploads\/2024\/10\/9-1024x1024.png 1024w, https:\/\/fcballkani.com\/wp-content\/uploads\/2024\/10\/9-300x300.png 300w, https:\/\/fcballkani.com\/wp-content\/uploads\/2024\/10\/9-150x150.png 150w, https:\/\/fcballkani.com\/wp-content\/uploads\/2024\/10\/9-768x768.png 768w, https:\/\/fcballkani.com\/wp-content\/uploads\/2024\/10\/9-1536x1536.png 1536w, https:\/\/fcballkani.com\/wp-content\/uploads\/2024\/10\/9-12x12.png 12w, https:\/\/fcballkani.com\/wp-content\/uploads\/2024\/10\/9.png 2000w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d1ab6fe\" data-id=\"d1ab6fe\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6671e42 elementor-widget elementor-widget-heading\" data-id=\"6671e42\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Third jersey<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2b81b25 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2b81b25\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-016e86e\" data-id=\"016e86e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9f92972 elementor-widget elementor-widget-heading\" data-id=\"9f92972\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Gallery <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4273906 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4273906\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8fa2cbd\" data-id=\"8fa2cbd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bc7d31e elementor-skin-carousel elementor-arrows-yes elementor-pagination-type-bullets elementor-pagination-position-outside elementor-widget elementor-widget-media-carousel\" data-id=\"bc7d31e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_per_view&quot;:&quot;2&quot;,&quot;skin&quot;:&quot;carousel&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;show_arrows&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"media-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.facebook.com\/photo?fbid=1181060910693452&#038;set=pcb.1181061030693440\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"480416211_18034888292618265_8765069987502389907_n\" style=\"background-image: url(&#039;https:\/\/fcballkani.com\/wp-content\/uploads\/2025\/02\/480416211_18034888292618265_8765069987502389907_n.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.facebook.com\/photo\/?fbid=1128185805980963&#038;set=pcb.1128186682647542\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"471153589_1128185809314296_2048150693255109135_n\" style=\"background-image: url(&#039;https:\/\/fcballkani.com\/wp-content\/uploads\/2024\/12\/471153589_1128185809314296_2048150693255109135_n.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.facebook.com\/photo\/?fbid=1126658682800342&#038;set=pcb.1126658826133661\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"470361419_18026661818618265_1936352123605134838_n\" style=\"background-image: url(&#039;https:\/\/fcballkani.com\/wp-content\/uploads\/2024\/12\/470361419_18026661818618265_1936352123605134838_n.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.facebook.chttps:\/\/www.facebook.com\/photo\/?fbid=1123988029734074&#038;set=pcb.1123988149734062om\/photo\/?fbid=1083310663801811&#038;set=pcb.1083310797135131\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"470248352_18026244728618265_4511838693749432163_n\" style=\"background-image: url(&#039;https:\/\/fcballkani.com\/wp-content\/uploads\/2024\/12\/470248352_18026244728618265_4511838693749432163_n.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.facebook.com\/photo\/?fbid=1120336740099203&#038;set=pcb.1120336880099189\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"469716751_18025657706618265_1182872894568050343_n\" style=\"background-image: url(&#039;https:\/\/fcballkani.com\/wp-content\/uploads\/2024\/12\/469716751_18025657706618265_1182872894568050343_n.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.facebook.com\/photo\/?fbid=1117338767065667&#038;set=pcb.1117338873732323\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"469214624_18025160156618265_9098582826019038087_n\" style=\"background-image: url(&#039;https:\/\/fcballkani.com\/wp-content\/uploads\/2024\/12\/469214624_18025160156618265_9098582826019038087_n.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.facebook.com\/photo\/?fbid=1108628877936656&#038;set=pcb.1108629001269977\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"468122654_18023768555618265_4036141647202052587_n\" style=\"background-image: url(&#039;https:\/\/fcballkani.com\/wp-content\/uploads\/2024\/12\/468122654_18023768555618265_4036141647202052587_n.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.facebook.com\/photo\/?fbid=1106359574830253&#038;set=pcb.1106359678163576\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"467763082_18023386706618265_1372988811866774635_n\" style=\"background-image: url(&#039;https:\/\/fcballkani.com\/wp-content\/uploads\/2024\/12\/467763082_18023386706618265_1372988811866774635_n.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.facebook.com\/photo\/?fbid=1104699778329566&#038;set=pcb.1104699834996227\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"467191904_18023143487618265_2654852805604493683_n\" style=\"background-image: url(&#039;https:\/\/fcballkani.com\/wp-content\/uploads\/2024\/12\/467191904_18023143487618265_2654852805604493683_n.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.facebook.com\/photo\/?fbid=1103212168478327&#038;set=pcb.1103219121810965\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"467509353_1103212425144968_8185416285218798112_n (1)\" style=\"background-image: url(&#039;https:\/\/fcballkani.com\/wp-content\/uploads\/2024\/12\/467509353_1103212425144968_8185416285218798112_n-1.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.facebook.com\/photo\/?fbid=1101666245299586&#038;set=pcb.1101667705299440\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"466785269_1101666298632914_4721542318102310286_n\" style=\"background-image: url(&#039;https:\/\/fcballkani.com\/wp-content\/uploads\/2024\/12\/466785269_1101666298632914_4721542318102310286_n.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.facebook.com\/photo\/?fbid=1095331639266380&#038;set=pcb.1095331755933035\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"466359017_18021649697618265_4972628264623640200_n\" style=\"background-image: url(&#039;https:\/\/fcballkani.com\/wp-content\/uploads\/2024\/12\/466359017_18021649697618265_4972628264623640200_n.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.facebook.com\/photo\/?fbid=1083310663801811&#038;set=pcb.1083310797135131\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"464178070_18019642250618265_5524750707673154594_n\" style=\"background-image: url(&#039;https:\/\/fcballkani.com\/wp-content\/uploads\/2024\/10\/464178070_18019642250618265_5524750707673154594_n.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.facebook.com\/photo\/?fbid=1080784100721134&#038;set=pcb.1080784974054380\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"464083236_1080785214054356_4145193647565085256_n\" style=\"background-image: url(&#039;https:\/\/fcballkani.com\/wp-content\/uploads\/2024\/10\/464083236_1080785214054356_4145193647565085256_n.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.facebook.com\/photo\/?fbid=1075283317937879&#038;set=pcb.1075283734604504\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"462765224_1075283484604529_4814703774832344971_n\" style=\"background-image: url(&#039;https:\/\/fcballkani.com\/wp-content\/uploads\/2024\/10\/462765224_1075283484604529_4814703774832344971_n.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.facebook.com\/photo\/?fbid=1071735241626020&#038;set=pcb.1071735368292674\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"462536378_18017792669618265_5896715564138787770_n\" style=\"background-image: url(&#039;https:\/\/fcballkani.com\/wp-content\/uploads\/2024\/10\/462536378_18017792669618265_5896715564138787770_n.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.facebook.com\/photo?fbid=1069317828534428&#038;set=pcb.1069317935201084\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"462258041_18017410739618265_6558101277656737315_n\" style=\"background-image: url(&#039;https:\/\/fcballkani.com\/wp-content\/uploads\/2024\/10\/462258041_18017410739618265_6558101277656737315_n.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.facebook.com\/photo\/?fbid=1066034455529432&#038;set=pcb.1066034595529418\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"461935012_18016848386618265_8422177787474341220_n\" style=\"background-image: url(&#039;https:\/\/fcballkani.com\/wp-content\/uploads\/2024\/10\/461935012_18016848386618265_8422177787474341220_n.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.facebook.com\/photo\/?fbid=1061904285942449&#038;set=pcb.1061904339275777\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"461324656_18016213316618265_1126597255956577307_n\" style=\"background-image: url(&#039;https:\/\/fcballkani.com\/wp-content\/uploads\/2024\/10\/461324656_18016213316618265_1126597255956577307_n.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.facebook.com\/photo\/?fbid=1059321996200678&#038;set=pcb.1059324326200445\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"461212757_1059322009534010_5078400053524371425_n\" style=\"background-image: url(&#039;https:\/\/fcballkani.com\/wp-content\/uploads\/2024\/10\/461212757_1059322009534010_5078400053524371425_n.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.facebook.com\/photo\/?fbid=1052673960198815&#038;set=pcb.1052675050198706\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"459588384_1052675296865348_3560048648749292898_n\" style=\"background-image: url(&#039;https:\/\/fcballkani.com\/wp-content\/uploads\/2024\/10\/459588384_1052675296865348_3560048648749292898_n.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.facebook.com\/photo\/?fbid=1050991740367037&#038;set=pcb.1050991920367019\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"459300430_18014539817618265_6522994798724192975_n\" style=\"background-image: url(&#039;https:\/\/fcballkani.com\/wp-content\/uploads\/2024\/10\/459300430_18014539817618265_6522994798724192975_n.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Previous\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Next\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-85b15d8 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"85b15d8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-eb31bf0\" data-id=\"eb31bf0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4764677 elementor-cta--skin-cover elementor-cta--valign-bottom elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"4764677\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<a class=\"elementor-cta\" href=\"https:\/\/www.facebook.com\/photo\/?fbid=925596622906550&#038;set=pcb.925598269573052\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/fcballkani.com\/wp-content\/uploads\/2024\/03\/420199467_925596569573222_1026369179031010981_n.jpg);\" role=\"img\" aria-label=\"420199467_925596569573222_1026369179031010981_n\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item elementor-animated-item--enter-from-bottom\">\n\t\t\t\t\t\tSt\u00ebrvitje \ud83e\udde1\u2705\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-20aad3c elementor-cta--skin-cover elementor-cta--valign-bottom elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"20aad3c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<a class=\"elementor-cta\" href=\"https:\/\/www.facebook.com\/photo\/?fbid=898855318914014&#038;set=pcb.898856332247246\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/fcballkani.com\/wp-content\/uploads\/2024\/02\/428642101_898856572247222_4615085359891733736_n.jpg);\" role=\"img\" aria-label=\"428642101_898856572247222_4615085359891733736_n\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item elementor-animated-item--enter-from-bottom\">\n\t\t\t\t\t\tSt\u00ebrvitje \ud83e\udde1\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0d6ed4f elementor-cta--skin-cover elementor-cta--valign-bottom elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"0d6ed4f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<a class=\"elementor-cta\" href=\"https:\/\/www.facebook.com\/photo\/?fbid=893744242758455&#038;set=pcb.893745496091663\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/fcballkani.com\/wp-content\/uploads\/2024\/02\/417512396_893744192758460_6093610325170725865_n.jpg);\" role=\"img\" aria-label=\"417512396_893744192758460_6093610325170725865_n\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item elementor-animated-item--enter-from-bottom\">\n\t\t\t\t\t\tFoto nga ndeshja kund\u00eb FC Liris\u00eb \ud83e\udde1\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-e46b446\" data-id=\"e46b446\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aab8cb4 elementor-cta--skin-cover elementor-cta--valign-bottom elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"aab8cb4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<a class=\"elementor-cta\" href=\"https:\/\/www.facebook.com\/photo\/?fbid=888175453315334&#038;set=pcb.888177826648430\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/fcballkani.com\/wp-content\/uploads\/2024\/03\/430023706_912178977581648_3373673251552231597_n-1024x683.jpg);\" role=\"img\" aria-label=\"430023706_912178977581648_3373673251552231597_n\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item elementor-animated-item--enter-from-bottom\">\n\t\t\t\t\t\tFoto nga ndeshja kund\u00ebr KF V\u00ebllaznimit \ud83e\udde1\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a1e2fad elementor-cta--skin-cover elementor-cta--valign-bottom elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"a1e2fad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<a class=\"elementor-cta\" href=\"https:\/\/www.facebook.com\/photo\/?fbid=912177214248491&#038;set=pcb.912178664248346\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/fcballkani.com\/wp-content\/uploads\/2024\/02\/417497180_905046331628246_6974487194483040418_n.jpg);\" role=\"img\" aria-label=\"417497180_905046331628246_6974487194483040418_n\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item elementor-animated-item--enter-from-bottom\">\n\t\t\t\t\t\tT\u00eb gjith\u00eb besimtar\u00ebve Musliman, urime Muaji i Shenjt\u00eb i Ramazanit! \t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5644990 elementor-cta--skin-cover elementor-cta--valign-bottom elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"5644990\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<a class=\"elementor-cta\" href=\"https:\/\/www.facebook.com\/photo\/?fbid=888175453315334&#038;set=pcb.888177826648430\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/fcballkani.com\/wp-content\/uploads\/2024\/02\/417702921_888175296648683_7903978786563044115_n.jpg);\" role=\"img\" aria-label=\"417702921_888175296648683_7903978786563044115_n\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item elementor-animated-item--enter-from-bottom\">\n\t\t\t\t\t\tFoto nga ndeshja kund\u00ebr KF V\u00ebllaznimit \ud83e\udde1\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-41f619f\" data-id=\"41f619f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a5b039 elementor-cta--skin-cover elementor-cta--valign-bottom elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"7a5b039\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<a class=\"elementor-cta\" href=\"https:\/\/www.facebook.com\/photo\/?fbid=913476147451931&#038;set=pcb.913477794118433\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/fcballkani.com\/wp-content\/uploads\/2024\/03\/432333002_913476054118607_5412091299613240670_n-1024x683.jpg);\" role=\"img\" aria-label=\"432333002_913476054118607_5412091299613240670_n\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item elementor-animated-item--enter-from-bottom\">\n\t\t\t\t\t\tFoto nga ndeshja kund\u00ebr FC Malishev\u00ebs \ud83e\udde1\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c47116 elementor-cta--skin-cover elementor-cta--valign-bottom elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"0c47116\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<a class=\"elementor-cta\" href=\"https:\/\/www.facebook.com\/photo\/?fbid=871673191632227&#038;set=pcb.871677691631777\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/fcballkani.com\/wp-content\/uploads\/2024\/01\/417474930_871673134965566_3076042533144239737_n.jpg);\" role=\"img\" aria-label=\"417474930_871673134965566_3076042533144239737_n\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item elementor-animated-item--enter-from-bottom\">\n\t\t\t\t\t\tP\u00ebrgaditjet n\u00eb Antalya kan\u00eb filluar \ud83d\ude0d\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c7b4fa elementor-cta--skin-cover elementor-cta--valign-bottom elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"2c7b4fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<a class=\"elementor-cta\" href=\"https:\/\/www.facebook.com\/photo\/?fbid=830918132374400&#038;set=pcb.830919125707634\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/fcballkani.com\/wp-content\/uploads\/2023\/11\/402195528_830918095707737_4171847636360524953_n-1-1024x683.jpg);\" role=\"img\" aria-label=\"402195528_830918095707737_4171847636360524953_n\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item elementor-animated-item--enter-from-bottom\">\n\t\t\t\t\t\tPas dy dit\u00ebve pushim ekipi i \u00ebsht\u00eb rikthyer sot st\u00ebrvitjeve \ud83e\udde1\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3c603e2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3c603e2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2ae95c7\" data-id=\"2ae95c7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b0d0ab elementor-widget elementor-widget-heading\" data-id=\"4b0d0ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">News<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b67776b elementor-posts--align-left elementor-grid-3 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-widget elementor-widget-posts\" data-id=\"b67776b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;classic_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;classic_columns&quot;:&quot;3&quot;,&quot;classic_columns_tablet&quot;:&quot;2&quot;,&quot;classic_columns_mobile&quot;:&quot;1&quot;,&quot;classic_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.classic\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-classic elementor-grid\" role=\"list\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-19644 post type-post status-publish format-standard has-post-thumbnail hentry category-uncategorized\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/fcballkani.com\/en\/me-moral-te-larte-pergatitemi-per-duelin-e-pare-gjysmefinal-ne-kupe\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1333\" height=\"2000\" src=\"https:\/\/fcballkani.com\/wp-content\/uploads\/2026\/04\/img_6572.jpg\" class=\"attachment-full size-full wp-image-19643\" alt=\"\" srcset=\"https:\/\/fcballkani.com\/wp-content\/uploads\/2026\/04\/img_6572.jpg 1333w, https:\/\/fcballkani.com\/wp-content\/uploads\/2026\/04\/img_6572-200x300.jpg 200w, https:\/\/fcballkani.com\/wp-content\/uploads\/2026\/04\/img_6572-682x1024.jpg 682w, https:\/\/fcballkani.com\/wp-content\/uploads\/2026\/04\/img_6572-768x1152.jpg 768w, https:\/\/fcballkani.com\/wp-content\/uploads\/2026\/04\/img_6572-1024x1536.jpg 1024w, https:\/\/fcballkani.com\/wp-content\/uploads\/2026\/04\/img_6572-8x12.jpg 8w\" sizes=\"(max-width: 1333px) 100vw, 1333px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/fcballkani.com\/en\/me-moral-te-larte-pergatitemi-per-duelin-e-pare-gjysmefinal-ne-kupe\/\" >\n\t\t\t\tMe moral t\u00eb lart\u00eb, p\u00ebrgatitemi p\u00ebr duelin e par\u00eb gjysm\u00ebfinal n\u00eb kup\u00eb\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tApril 6, 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/fcballkani.com\/en\/me-moral-te-larte-pergatitemi-per-duelin-e-pare-gjysmefinal-ne-kupe\/\" aria-label=\"Read more about Me moral t\u00eb lart\u00eb, p\u00ebrgatitemi p\u00ebr duelin e par\u00eb gjysm\u00ebfinal n\u00eb kup\u00eb\" tabindex=\"-1\" >\n\t\t\t\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-19630 post type-post status-publish format-standard has-post-thumbnail hentry category-uncategorized\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/fcballkani.com\/en\/bleart-tolaj-ishte-nje-moment-i-cmendur\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1292\" height=\"1615\" src=\"https:\/\/fcballkani.com\/wp-content\/uploads\/2026\/04\/img_6500.jpg\" class=\"attachment-full size-full wp-image-19640\" alt=\"\" srcset=\"https:\/\/fcballkani.com\/wp-content\/uploads\/2026\/04\/img_6500.jpg 1292w, https:\/\/fcballkani.com\/wp-content\/uploads\/2026\/04\/img_6500-240x300.jpg 240w, https:\/\/fcballkani.com\/wp-content\/uploads\/2026\/04\/img_6500-819x1024.jpg 819w, https:\/\/fcballkani.com\/wp-content\/uploads\/2026\/04\/img_6500-768x960.jpg 768w, https:\/\/fcballkani.com\/wp-content\/uploads\/2026\/04\/img_6500-1229x1536.jpg 1229w, https:\/\/fcballkani.com\/wp-content\/uploads\/2026\/04\/img_6500-10x12.jpg 10w\" sizes=\"(max-width: 1292px) 100vw, 1292px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/fcballkani.com\/en\/bleart-tolaj-ishte-nje-moment-i-cmendur\/\" >\n\t\t\t\tTolaj: &#8220;Ishte nj\u00eb moment i \u00e7mendur&#8221;\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tApril 4, 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/fcballkani.com\/en\/bleart-tolaj-ishte-nje-moment-i-cmendur\/\" aria-label=\"Read more about Tolaj: &#8220;Ishte nj\u00eb moment i \u00e7mendur&#8221;\" tabindex=\"-1\" >\n\t\t\t\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-19628 post type-post status-publish format-standard has-post-thumbnail hentry category-uncategorized\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/fcballkani.com\/en\/almir-kryeziu-fitoret-ne-minutat-e-fundit-kane-shije-krejt-tjeter\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1440\" height=\"1800\" src=\"https:\/\/fcballkani.com\/wp-content\/uploads\/2026\/04\/img_6497.jpg\" class=\"attachment-full size-full wp-image-19637\" alt=\"\" srcset=\"https:\/\/fcballkani.com\/wp-content\/uploads\/2026\/04\/img_6497.jpg 1440w, https:\/\/fcballkani.com\/wp-content\/uploads\/2026\/04\/img_6497-240x300.jpg 240w, https:\/\/fcballkani.com\/wp-content\/uploads\/2026\/04\/img_6497-819x1024.jpg 819w, https:\/\/fcballkani.com\/wp-content\/uploads\/2026\/04\/img_6497-768x960.jpg 768w, https:\/\/fcballkani.com\/wp-content\/uploads\/2026\/04\/img_6497-1229x1536.jpg 1229w, https:\/\/fcballkani.com\/wp-content\/uploads\/2026\/04\/img_6497-10x12.jpg 10w\" sizes=\"(max-width: 1440px) 100vw, 1440px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/fcballkani.com\/en\/almir-kryeziu-fitoret-ne-minutat-e-fundit-kane-shije-krejt-tjeter\/\" >\n\t\t\t\tKryeziu: \u201cFitoret n\u00eb minutat e fundit kan\u00eb shije krejt tjet\u00ebr\u201d\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tApril 4, 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/fcballkani.com\/en\/almir-kryeziu-fitoret-ne-minutat-e-fundit-kane-shije-krejt-tjeter\/\" aria-label=\"Read more about Kryeziu: \u201cFitoret n\u00eb minutat e fundit kan\u00eb shije krejt tjet\u00ebr\u201d\" tabindex=\"-1\" >\n\t\t\t\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-19625 post type-post status-publish format-standard has-post-thumbnail hentry category-uncategorized\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/fcballkani.com\/en\/tolaj-ne-frymen-e-fundit-fitore-dramatike-ndaj-dukagjinit\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1440\" height=\"1800\" src=\"https:\/\/fcballkani.com\/wp-content\/uploads\/2026\/04\/img_6498.jpg\" class=\"attachment-full size-full wp-image-19636\" alt=\"\" srcset=\"https:\/\/fcballkani.com\/wp-content\/uploads\/2026\/04\/img_6498.jpg 1440w, https:\/\/fcballkani.com\/wp-content\/uploads\/2026\/04\/img_6498-240x300.jpg 240w, https:\/\/fcballkani.com\/wp-content\/uploads\/2026\/04\/img_6498-819x1024.jpg 819w, https:\/\/fcballkani.com\/wp-content\/uploads\/2026\/04\/img_6498-768x960.jpg 768w, https:\/\/fcballkani.com\/wp-content\/uploads\/2026\/04\/img_6498-1229x1536.jpg 1229w, https:\/\/fcballkani.com\/wp-content\/uploads\/2026\/04\/img_6498-10x12.jpg 10w\" sizes=\"(max-width: 1440px) 100vw, 1440px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/fcballkani.com\/en\/tolaj-ne-frymen-e-fundit-fitore-dramatike-ndaj-dukagjinit\/\" >\n\t\t\t\tTolaj n\u00eb frym\u00ebn e fundit, fitore dramatike ndaj Dukagjinit!\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tApril 4, 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/fcballkani.com\/en\/tolaj-ne-frymen-e-fundit-fitore-dramatike-ndaj-dukagjinit\/\" aria-label=\"Read more about Tolaj n\u00eb frym\u00ebn e fundit, fitore dramatike ndaj Dukagjinit!\" tabindex=\"-1\" >\n\t\t\t\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-19621 post type-post status-publish format-standard has-post-thumbnail hentry category-uncategorized\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/fcballkani.com\/en\/jashanica-maksimumi-ne-fushe-per-tu-rikthyer-te-fitoret\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"932\" height=\"960\" src=\"https:\/\/fcballkani.com\/wp-content\/uploads\/2026\/04\/img_6447.jpg\" class=\"attachment-full size-full wp-image-19620\" alt=\"\" srcset=\"https:\/\/fcballkani.com\/wp-content\/uploads\/2026\/04\/img_6447.jpg 932w, https:\/\/fcballkani.com\/wp-content\/uploads\/2026\/04\/img_6447-291x300.jpg 291w, https:\/\/fcballkani.com\/wp-content\/uploads\/2026\/04\/img_6447-768x791.jpg 768w, https:\/\/fcballkani.com\/wp-content\/uploads\/2026\/04\/img_6447-12x12.jpg 12w\" sizes=\"(max-width: 932px) 100vw, 932px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/fcballkani.com\/en\/jashanica-maksimumi-ne-fushe-per-tu-rikthyer-te-fitoret\/\" >\n\t\t\t\tJashanica: \u201cMaksimumi n\u00eb fush\u00eb p\u00ebr t\u2019u rikthyer te fitoret\u201d\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tApril 3, 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/fcballkani.com\/en\/jashanica-maksimumi-ne-fushe-per-tu-rikthyer-te-fitoret\/\" aria-label=\"Read more about Jashanica: \u201cMaksimumi n\u00eb fush\u00eb p\u00ebr t\u2019u rikthyer te fitoret\u201d\" tabindex=\"-1\" >\n\t\t\t\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-19618 post type-post status-publish format-standard has-post-thumbnail hentry category-uncategorized\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/fcballkani.com\/en\/ekipi-gati-per-rikthimin-ne-kampionat\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1440\" height=\"960\" src=\"https:\/\/fcballkani.com\/wp-content\/uploads\/2026\/04\/img_6444.jpg\" class=\"attachment-full size-full wp-image-19617\" alt=\"\" srcset=\"https:\/\/fcballkani.com\/wp-content\/uploads\/2026\/04\/img_6444.jpg 1440w, https:\/\/fcballkani.com\/wp-content\/uploads\/2026\/04\/img_6444-300x200.jpg 300w, https:\/\/fcballkani.com\/wp-content\/uploads\/2026\/04\/img_6444-1024x683.jpg 1024w, https:\/\/fcballkani.com\/wp-content\/uploads\/2026\/04\/img_6444-768x512.jpg 768w, https:\/\/fcballkani.com\/wp-content\/uploads\/2026\/04\/img_6444-18x12.jpg 18w\" sizes=\"(max-width: 1440px) 100vw, 1440px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/fcballkani.com\/en\/ekipi-gati-per-rikthimin-ne-kampionat\/\" >\n\t\t\t\tEkipi gati p\u00ebr rikthimin n\u00eb kampionat&nbsp;\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tApril 3, 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/fcballkani.com\/en\/ekipi-gati-per-rikthimin-ne-kampionat\/\" aria-label=\"Read more about Ekipi gati p\u00ebr rikthimin n\u00eb kampionat&nbsp;\" tabindex=\"-1\" >\n\t\t\t\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Ndeshja e radh\u00ebs M\u00ebso m\u00eb shum\u00eb FC Ballkani VS KF Prishtina e Re Lokacioni: Stadiumi i Qytetit, Suharek\u00eb Data: 17.05.2026 Days Hours Minutes Seconds Biletat<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-1746","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ballkani - FC BALLKANI<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fcballkani.com\/en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ballkani - FC BALLKANI\" \/>\n<meta property=\"og:description\" content=\"Ndeshja e radh\u00ebs M\u00ebso m\u00eb shum\u00eb FC Ballkani VS KF Prishtina e Re Lokacioni: Stadiumi i Qytetit, Suharek\u00eb Data: 17.05.2026 Days Hours Minutes Seconds Biletat\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fcballkani.com\/en\/\" \/>\n<meta property=\"og:site_name\" content=\"FC BALLKANI\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/fcballkani\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-11T08:21:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fcballkani.com\/wp-content\/uploads\/2022\/07\/fc-ballkani.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/fcballkani.com\/\",\"url\":\"https:\/\/fcballkani.com\/\",\"name\":\"Ballkani - FC BALLKANI\",\"isPartOf\":{\"@id\":\"https:\/\/fcballkani.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/fcballkani.com\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/fcballkani.com\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/fcballkani.com\/wp-content\/uploads\/2022\/07\/fc-ballkani.png\",\"datePublished\":\"2022-07-15T07:16:02+00:00\",\"dateModified\":\"2026-05-11T08:21:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/fcballkani.com\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/fcballkani.com\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/fcballkani.com\/#primaryimage\",\"url\":\"https:\/\/fcballkani.com\/wp-content\/uploads\/2022\/07\/fc-ballkani.png\",\"contentUrl\":\"https:\/\/fcballkani.com\/wp-content\/uploads\/2022\/07\/fc-ballkani.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/fcballkani.com\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/fcballkani.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ballkani\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/fcballkani.com\/#website\",\"url\":\"https:\/\/fcballkani.com\/\",\"name\":\"FC BALLKANI\",\"description\":\"Football Club\",\"publisher\":{\"@id\":\"https:\/\/fcballkani.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/fcballkani.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/fcballkani.com\/#organization\",\"name\":\"FC Ballkani\",\"url\":\"https:\/\/fcballkani.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/fcballkani.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/fcballkani.com\/wp-content\/uploads\/2022\/07\/fc-ballkani.png\",\"contentUrl\":\"https:\/\/fcballkani.com\/wp-content\/uploads\/2022\/07\/fc-ballkani.png\",\"width\":642,\"height\":642,\"caption\":\"FC Ballkani\"},\"image\":{\"@id\":\"https:\/\/fcballkani.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/fcballkani\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ballkani - FC BALLKANI","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fcballkani.com\/en\/","og_locale":"en_US","og_type":"article","og_title":"Ballkani - FC BALLKANI","og_description":"Ndeshja e radh\u00ebs M\u00ebso m\u00eb shum\u00eb FC Ballkani VS KF Prishtina e Re Lokacioni: Stadiumi i Qytetit, Suharek\u00eb Data: 17.05.2026 Days Hours Minutes Seconds Biletat","og_url":"https:\/\/fcballkani.com\/en\/","og_site_name":"FC BALLKANI","article_publisher":"https:\/\/www.facebook.com\/fcballkani","article_modified_time":"2026-05-11T08:21:55+00:00","og_image":[{"url":"https:\/\/fcballkani.com\/wp-content\/uploads\/2022\/07\/fc-ballkani.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fcballkani.com\/","url":"https:\/\/fcballkani.com\/","name":"Ballkani - FC BALLKANI","isPartOf":{"@id":"https:\/\/fcballkani.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fcballkani.com\/#primaryimage"},"image":{"@id":"https:\/\/fcballkani.com\/#primaryimage"},"thumbnailUrl":"https:\/\/fcballkani.com\/wp-content\/uploads\/2022\/07\/fc-ballkani.png","datePublished":"2022-07-15T07:16:02+00:00","dateModified":"2026-05-11T08:21:55+00:00","breadcrumb":{"@id":"https:\/\/fcballkani.com\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fcballkani.com\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/fcballkani.com\/#primaryimage","url":"https:\/\/fcballkani.com\/wp-content\/uploads\/2022\/07\/fc-ballkani.png","contentUrl":"https:\/\/fcballkani.com\/wp-content\/uploads\/2022\/07\/fc-ballkani.png"},{"@type":"BreadcrumbList","@id":"https:\/\/fcballkani.com\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fcballkani.com\/"},{"@type":"ListItem","position":2,"name":"Ballkani"}]},{"@type":"WebSite","@id":"https:\/\/fcballkani.com\/#website","url":"https:\/\/fcballkani.com\/","name":"FC BALLKANI","description":"Football Club","publisher":{"@id":"https:\/\/fcballkani.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fcballkani.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/fcballkani.com\/#organization","name":"FC Ballkani","url":"https:\/\/fcballkani.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/fcballkani.com\/#\/schema\/logo\/image\/","url":"https:\/\/fcballkani.com\/wp-content\/uploads\/2022\/07\/fc-ballkani.png","contentUrl":"https:\/\/fcballkani.com\/wp-content\/uploads\/2022\/07\/fc-ballkani.png","width":642,"height":642,"caption":"FC Ballkani"},"image":{"@id":"https:\/\/fcballkani.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/fcballkani"]}]}},"_links":{"self":[{"href":"https:\/\/fcballkani.com\/en\/wp-json\/wp\/v2\/pages\/1746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fcballkani.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fcballkani.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fcballkani.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fcballkani.com\/en\/wp-json\/wp\/v2\/comments?post=1746"}],"version-history":[{"count":20,"href":"https:\/\/fcballkani.com\/en\/wp-json\/wp\/v2\/pages\/1746\/revisions"}],"predecessor-version":[{"id":19671,"href":"https:\/\/fcballkani.com\/en\/wp-json\/wp\/v2\/pages\/1746\/revisions\/19671"}],"wp:attachment":[{"href":"https:\/\/fcballkani.com\/en\/wp-json\/wp\/v2\/media?parent=1746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}